{"id":49997,"date":"2022-04-24T16:39:05","date_gmt":"2022-04-24T23:39:05","guid":{"rendered":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg"},"modified":"2022-04-24T16:39:05","modified_gmt":"2022-04-24T23:39:05","slug":"mexxr-remede-spa-8502-hor-clsc-2","status":"inherit","type":"attachment","link":"https:\/\/www.inmexico.com\/es\/mexxr-remede-spa-8502-hor-clsc-2\/","title":{"rendered":"mexxr-remede-spa-8502-hor-clsc"},"author":13219,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"class_list":["post-49997","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>mexxr-remede-spa-8502-hor-clsc - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mexxr-remede-spa-8502-hor-clsc - InMexico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1336\" \/>\n\t<meta property=\"og:image:height\" content=\"890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\",\"url\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\",\"name\":\"mexxr-remede-spa-8502-hor-clsc - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2022-04-24T23:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mexxr-remede-spa-8502-hor-clsc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mexxr-remede-spa-8502-hor-clsc - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","og_locale":"es_MX","og_type":"article","og_title":"mexxr-remede-spa-8502-hor-clsc - InMexico","og_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","og_image":[{"width":1336,"height":890,"url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inmexicocom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","name":"mexxr-remede-spa-8502-hor-clsc - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2022-04-24T23:39:05+00:00","breadcrumb":{"@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"mexxr-remede-spa-8502-hor-clsc"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-300x200.jpg 300w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-1024x682.jpg 1024w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-768x512.jpg 768w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-100x67.jpg 100w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-864x576.jpg 864w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-1200x799.jpg 1200w, https:\/\/images.inmexico.com\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg 1336w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1336,"height":890,"file":"2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","sizes":{"medium":{"file":"mexxr-remede-spa-8502-hor-clsc-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-300x200.jpg"},"large":{"file":"mexxr-remede-spa-8502-hor-clsc-1024x682.jpg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-1024x682.jpg"},"thumbnail":{"file":"mexxr-remede-spa-8502-hor-clsc-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-150x150.jpg"},"medium_large":{"file":"mexxr-remede-spa-8502-hor-clsc-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-768x512.jpg"},"us_screen":{"file":"mexxr-remede-spa-8502-hor-clsc-450x890.jpg","width":450,"height":890,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-450x890.jpg"},"post-thumbnail":{"file":"mexxr-remede-spa-8502-hor-clsc-100x67.jpg","width":100,"height":67,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-100x67.jpg"},"entry":{"file":"mexxr-remede-spa-8502-hor-clsc-864x576.jpg","width":864,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-864x576.jpg"},"entry-cropped":{"file":"mexxr-remede-spa-8502-hor-clsc-864x483.jpg","width":864,"height":483,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-864x483.jpg"},"entry-fullwidth":{"file":"mexxr-remede-spa-8502-hor-clsc-1200x799.jpg","width":1200,"height":799,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-1200x799.jpg"},"entry-cropped-fullwidth":{"file":"mexxr-remede-spa-8502-hor-clsc-1200x671.jpg","width":1200,"height":671,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-1200x671.jpg"},"rpwe-thumbnail":{"file":"mexxr-remede-spa-8502-hor-clsc-45x45.jpg","width":45,"height":45,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc-45x45.jpg"},"full":{"file":"mexxr-remede-spa-8502-hor-clsc.jpg","width":1336,"height":890,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2022\/04\/mexxr-remede-spa-8502-hor-clsc.jpg","_links":{"self":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media\/49997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/users\/13219"}]}}