{"id":51938,"date":"2023-02-13T08:02:23","date_gmt":"2023-02-13T15:02:23","guid":{"rendered":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg"},"modified":"2023-02-13T08:02:23","modified_gmt":"2023-02-13T15:02:23","slug":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-2","status":"inherit","type":"attachment","link":"https:\/\/www.inmexico.com\/es\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-2\/","title":{"rendered":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4"},"author":13219,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"class_list":["post-51938","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\",\"url\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\",\"name\":\"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2023-02-13T15:02:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","og_locale":"es_MX","og_type":"article","og_title":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico","og_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","og_image":[{"width":800,"height":495,"url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inmexicocom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","name":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4 - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2023-02-13T15:02:23+00:00","breadcrumb":{"@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-300x186.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-300x186.jpg 300w, https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-768x475.jpg 768w, https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-100x62.jpg 100w, https:\/\/images.inmexico.com\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":495,"file":"2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","sizes":{"medium":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-300x186.jpg","width":300,"height":186,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-300x186.jpg"},"thumbnail":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-150x150.jpg"},"medium_large":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-768x475.jpg","width":768,"height":475,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-768x475.jpg"},"us_screen":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-450x495.jpg","width":450,"height":495,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-450x495.jpg"},"post-thumbnail":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-100x62.jpg","width":100,"height":62,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-100x62.jpg"},"entry-cropped":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-800x483.jpg","width":800,"height":483,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-800x483.jpg"},"rpwe-thumbnail":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-45x45.jpg","width":45,"height":45,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4-45x45.jpg"},"full":{"file":"el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","width":800,"height":495,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2023\/02\/el-dorado-golf-and-beach-club-4_2022-11-08-234540_41d112bd920265906afe9ffb530de2f4.jpg","_links":{"self":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media\/51938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/users\/13219"}]}}