{"id":26568,"date":"2017-10-09T09:00:20","date_gmt":"2017-10-09T16:00:20","guid":{"rendered":"https:\/\/www.inmexico.com\/es\/?p=26568"},"modified":"2017-10-06T20:27:21","modified_gmt":"2017-10-07T03:27:21","slug":"cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita","status":"publish","type":"post","link":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/","title":{"rendered":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita"},"content":{"rendered":"<p>En la exclusiva comunidad de Punta Mita se encuentran algunas de las propiedades m\u00e1s lujosas frente al mar de todo M\u00e9xico. A diferencia de las t\u00edpicas bodas de hotel, en las que ese d\u00eda tan especial se comparte (inevitablemente) con hu\u00e9spedes y otros curiosos espectadores, una boda en una villa en Punta Mita es sin\u00f3nimo de privacidad y exclusividad. Ubicadas en enclaves privados, estas villas de dise\u00f1o exclusivo ofrecen un nivel de confort inigualable, permitiendo que los novios pasen m\u00e1s tiempo con sus familiares y amigos, disfruten de una fiesta m\u00e1s larga, lleven a cabo todo tipo de eventos en un solo lugar, y tengan la libertad de personalizar hasta el \u00faltimo detalle de ese d\u00eda tan especial.<\/p>\n<p>Con paisajes espectaculares para sus fotos, amenidades de primer nivel para sus hu\u00e9spedes, chefs privados, cocineros, choferes y personal de limpieza, estas 4 propiedades no dejan ning\u00fan deseo sin satisfacer.<\/p>\n<p><a href=\"https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26561 size-large\" src=\"https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-1024x683.jpg 1024w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-450x300.jpg 450w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-300x200.jpg 300w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-768x512.jpg 768w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-100x67.jpg 100w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas-864x576.jpg 864w, https:\/\/images.inmexico.com\/2017\/10\/Casa-Entre-Rocas.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<h3><strong>Casa Entre Rocas<\/strong><\/h3>\n<p>Ubicada en el exclusivo desarrollo frente al mar de La Punta Estates, esta lujosa villa es el sitio ideal para llevar a cabo una boda tropical. Esta propiedad se caracteriza por sus espacios abiertos y ventilados con muebles contempor\u00e1neos en colores brillantes. Siete rec\u00e1maras estilo suite pueden acoger hasta 20 personas, y dos de ellas incluyen ba\u00f1eras al aire libre y acceso directo a la terraza. En el exterior se encuentra una magn\u00edfica piscina de borde infinito, un jacuzzi, una terraza en la azotea con un foso para fogatas y un jard\u00edn de yoga, comedores al aire libre, una parrilla, camastros, un bar, una sala de vapor y gimnasio. El personal de servicio incluye un chef personal, tres amas de llaves, dos meseros, un barman y un chofer.<\/p>\n<p>Precio: $7,000-$12,500 USD por noche<\/p>\n<p>Para m\u00e1s informaci\u00f3n, haga clic\u00a0<a href=\"https:\/\/www.luxuryretreats.com\/vacation-rentals\/mexico\/punta-mita\/la-punta-estates\/casa-entre-rocas-117182\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<h3><strong><a href=\"https:\/\/images.inmexico.com\/2017\/10\/majani-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26562 size-large\" src=\"https:\/\/images.inmexico.com\/2017\/10\/majani-3-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/images.inmexico.com\/2017\/10\/majani-3-1024x683.jpg 1024w, https:\/\/images.inmexico.com\/2017\/10\/majani-3-450x300.jpg 450w, https:\/\/images.inmexico.com\/2017\/10\/majani-3-300x200.jpg 300w, https:\/\/images.inmexico.com\/2017\/10\/majani-3-768x512.jpg 768w, https:\/\/images.inmexico.com\/2017\/10\/majani-3-100x67.jpg 100w, https:\/\/images.inmexico.com\/2017\/10\/majani-3-864x576.jpg 864w, https:\/\/images.inmexico.com\/2017\/10\/majani-3.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/strong><\/h3>\n<h3><strong>Casa Majani<\/strong><\/h3>\n<p>Parte de la exclusiva comunidad de Punta Estates, Casa Majani fue dise\u00f1ada por el arquitecto de fama mundial, Manolo Mestre, cuyo enfoque hol\u00edstico se ve reflejado en c\u00f3mo la simplicidad nativa de la propiedad y sus tonos c\u00e1lidos se complementan con comodidades modernas, dando como resultado una experiencia atractiva y meditativa. Casa Majani cuenta con seis rec\u00e1maras grandes, cada una con ba\u00f1o en suite. La lista de amenidades incluye dos piscinas conectadas, un bar que se extiende de la pared y que cuenta con una tabla de surf vintage restaurada, un foso para fogatas en la planta baja y una sala de fitness y yoga. Su reservaci\u00f3n incluye servicio de cocinero, conserje, ama de llaves, servicio de mayordomo y vigilante nocturno.<\/p>\n<p>Precio: $5,500-$13,300 USD\u00a0 por noche<\/p>\n<p>Para m\u00e1s informaci\u00f3n, haga clic <a href=\"https:\/\/www.luxuryretreats.com\/vacation-rentals\/mexico\/punta-mita\/la-punta-estates\/casa-majani-112015\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<h3><strong><a href=\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26563\" src=\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-1024x683.jpg 1024w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-450x300.jpg 450w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-300x200.jpg 300w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-768x512.jpg 768w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-100x67.jpg 100w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-864x576.jpg 864w, https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/strong><\/h3>\n<h3><strong>Villa Pacifica<\/strong><\/h3>\n<p>Ubicada en Ranchos Estates, la comunidad privada m\u00e1s exclusiva de Punta Mita, Villa Pacifica ofrece completo aislamiento a la orilla de un extenso tramo de playa de arena blanca. Dise\u00f1ada por el arquitecto Pepe de Iturbide, su estilo contempor\u00e1neo y sofisticado cuenta con un dise\u00f1o abierto, impresionantes elementos de agua y amplias \u00e1reas de estar al aire libre con vistas espectaculares. Las amenidades incluyen una piscina, jacuzzi, terraza exterior, \u00e1rea de comedor al aire libre y acceso a la playa. Su reservaci\u00f3n incluye un administrador, mayordomo, servicio de chef, servicio de lavander\u00eda, ama de llaves, seguridad las 24 horas del d\u00eda y mucho m\u00e1s. Con un total de cinco rec\u00e1maras, esta villa puede acoger a un total de 12 hu\u00e9spedes.<\/p>\n<p>Precio: $5,500-$11,500 USD por noche<\/p>\n<p>Para m\u00e1s informaci\u00f3n, haga clic <a href=\"https:\/\/www.luxuryretreats.com\/vacation-rentals\/mexico\/punta-mita\/los-ranchos\/villa-pacifica-114043\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<h3><strong><a href=\"https:\/\/images.inmexico.com\/2017\/10\/querencia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26564\" src=\"https:\/\/images.inmexico.com\/2017\/10\/querencia-1024x595.jpg\" alt=\"\" width=\"1024\" height=\"595\" srcset=\"https:\/\/images.inmexico.com\/2017\/10\/querencia-1024x595.jpg 1024w, https:\/\/images.inmexico.com\/2017\/10\/querencia-450x261.jpg 450w, https:\/\/images.inmexico.com\/2017\/10\/querencia-300x174.jpg 300w, https:\/\/images.inmexico.com\/2017\/10\/querencia-768x446.jpg 768w, https:\/\/images.inmexico.com\/2017\/10\/querencia-100x58.jpg 100w, https:\/\/images.inmexico.com\/2017\/10\/querencia-864x502.jpg 864w, https:\/\/images.inmexico.com\/2017\/10\/querencia.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/strong><\/h3>\n<h3><strong>Casa Querencia<\/strong><\/h3>\n<p>Esta propiedad \u00fanica est\u00e1 localizada en el enclave m\u00e1s nuevo y m\u00e1s exclusivo de Punta Mita. La casa se encuentra sobre una colina, ofreciendo vistas de 180 grados a la bah\u00eda, y sus piscinas de borde infinito ofrecen vistas al mar y una belleza infinita. Su arquitectura moderna, combinada con los ricos productos textiles, produce un aspecto tropical en esta propiedad de cinco rec\u00e1maras en suite. En el interior se encuentra una cocina con encimeras de granito, espacios interiores y exteriores que se integran de manera natural y techos con vigas de madera. En el exterior, las amenidades incluyen un exuberante jard\u00edn privado, un impresionante foso para fogatas, una caba\u00f1a de playa, una palapa al aire libre, una parrilla, un horno para pizzas, una terraza con hamacas y canchas de voleibol de playa y baloncesto. Su reservaci\u00f3n incluye un administrador, mayordomo, una persona encargada de la piscina, ama de llaves y chef.<\/p>\n<p>Precio: $4,500-$7,000 USD por noche<\/p>\n<p>Para m\u00e1s informaci\u00f3n, haga clic <a href=\"https:\/\/www.luxuryretreats.com\/vacation-rentals\/mexico\/punta-mita\/kupuri\/casa-querencia-113557\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Foto principal: Villa Pacifica<\/p>\n<p>Fotos:\u00a0<a href=\"https:\/\/www.luxuryretreats.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.luxuryretreats.com\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicadas en enclaves privados, estas villas de dise\u00f1o exclusivo ofrecen un nivel de confort inigualable, permitiendo que los novios pasen m\u00e1s tiempo con sus familiares y amigos, disfruten de una fiesta m\u00e1s larga, lleven a cabo todo tipo de eventos en un solo lugar, y tengan la libertad de personalizar hasta el \u00faltimo detalle de ese d\u00eda tan especial.<\/p>\n","protected":false},"author":4,"featured_media":26565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2076,1191,1186],"tags":[],"class_list":["post-26568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bodas","category-hospedese-5","category-puerto-vallarta-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico\" \/>\n<meta property=\"og:description\" content=\"Ubicadas en enclaves privados, estas villas de dise\u00f1o exclusivo ofrecen un nivel de confort inigualable, permitiendo que los novios pasen m\u00e1s tiempo con sus familiares y amigos, disfruten de una fiesta m\u00e1s larga, lleven a cabo todo tipo de eventos en un solo lugar, y tengan la libertad de personalizar hasta el \u00faltimo detalle de ese d\u00eda tan especial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-09T16:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Belen Molina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@inmexicocom\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Belen Molina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\"},\"author\":{\"name\":\"Belen Molina\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\"},\"headline\":\"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita\",\"datePublished\":\"2017-10-09T16:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\"},\"wordCount\":789,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg\",\"articleSection\":[\"Bodas\",\"Hosp\u00e9dese\",\"Puerto Vallarta &amp; Punta Mita\"],\"inLanguage\":\"es-MX\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\",\"url\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\",\"name\":\"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg\",\"datePublished\":\"2017-10-09T16:00:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage\",\"url\":\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg\",\"contentUrl\":\"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\",\"name\":\"Belen Molina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g\",\"caption\":\"Belen Molina\"},\"url\":\"https:\/\/www.inmexico.com\/es\/author\/belen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/","og_locale":"es_MX","og_type":"article","og_title":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico","og_description":"Ubicadas en enclaves privados, estas villas de dise\u00f1o exclusivo ofrecen un nivel de confort inigualable, permitiendo que los novios pasen m\u00e1s tiempo con sus familiares y amigos, disfruten de una fiesta m\u00e1s larga, lleven a cabo todo tipo de eventos en un solo lugar, y tengan la libertad de personalizar hasta el \u00faltimo detalle de ese d\u00eda tan especial.","og_url":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","article_published_time":"2017-10-09T16:00:20+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg","type":"image\/jpeg"}],"author":"Belen Molina","twitter_card":"summary_large_image","twitter_creator":"@inmexicocom","twitter_site":"@inmexicocom","twitter_misc":{"Written by":"Belen Molina","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#article","isPartOf":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/"},"author":{"name":"Belen Molina","@id":"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695"},"headline":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita","datePublished":"2017-10-09T16:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/"},"wordCount":789,"commentCount":0,"image":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage"},"thumbnailUrl":"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg","articleSection":["Bodas","Hosp\u00e9dese","Puerto Vallarta &amp; Punta Mita"],"inLanguage":"es-MX"},{"@type":"WebPage","@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/","url":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/","name":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage"},"image":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage"},"thumbnailUrl":"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg","datePublished":"2017-10-09T16:00:20+00:00","author":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695"},"breadcrumb":{"@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#primaryimage","url":"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg","contentUrl":"https:\/\/images.inmexico.com\/2017\/10\/villa-pacifica-cover.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.inmexico.com\/es\/bodas\/cuatro-impresionantes-villas-para-celebrar-una-lujosa-boda-en-punta-mita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro impresionantes villas para celebrar una lujosa boda en Punta Mita"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Person","@id":"https:\/\/www.inmexico.com\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695","name":"Belen Molina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g","caption":"Belen Molina"},"url":"https:\/\/www.inmexico.com\/es\/author\/belen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/26568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/comments?post=26568"}],"version-history":[{"count":2,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/26568\/revisions"}],"predecessor-version":[{"id":26570,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/26568\/revisions\/26570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media\/26565"}],"wp:attachment":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media?parent=26568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/categories?post=26568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/tags?post=26568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}