{"id":34132,"date":"2018-11-05T10:25:59","date_gmt":"2018-11-05T17:25:59","guid":{"rendered":"https:\/\/www.inmexico.com\/?p=34132"},"modified":"2018-11-05T21:59:46","modified_gmt":"2018-11-06T04:59:46","slug":"el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores","status":"publish","type":"post","link":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/","title":{"rendered":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores"},"content":{"rendered":"<p>Desde su creaci\u00f3n en 2007, el <a href=\"https:\/\/mayakobagolfclassic.com\/\">Mayakoba Golf Classic<\/a> ha hecho historia como uno de los mejores torneos en el PGA TOUR, tanto por sus participantes como por sus espectadores. Dado que es el primer evento del PGA TOUR que se celebra fuera de los Estados Unidos y Canad\u00e1, el torneo cuenta con el premio en dinero m\u00e1s grande (7.2 millones de d\u00f3lares) de cualquier otro torneo de golf en Latinoam\u00e9rica. Adem\u00e1s, es el \u00fanico evento profesional en Latinoam\u00e9rica en el que el campe\u00f3n recibe una invitaci\u00f3n para el Masters.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34108 alignleft\" src=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.55.11-AM.jpg\" alt=\"\" width=\"471\" height=\"529\" srcset=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.55.11-AM.jpg 572w, https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.55.11-AM-267x300.jpg 267w, https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.55.11-AM-100x112.jpg 100w, https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.55.11-AM-450x505.jpg 450w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/p>\n<p>El evento de este a\u00f1o, que se llevar\u00e1 a cabo del 5 al 11 de noviembre, contaraa con la presencia de 132 golfistas profesionales que competir\u00e1n en cuatro rondas en El Camale\u00f3n Golf Club, el campo de golf dise\u00f1ado por Greg Norman en la Riviera Maya.<\/p>\n<p>Sum\u00e1ndose a este evento tan esperado se encuentra el reciente anuncio de Jordan Speith, quien se compromete a competir en el evento de 2018. Actualmente, el tricampe\u00f3n se encuentra en el puesto No. 11 del ranking mundial de golf. Esta ser\u00e1 la primera aparici\u00f3n de su carrera en Mayakoba.<\/p>\n<p>Acompa\u00f1ado a Speith, otros ocho jugadores en la lista de los \u201ctop 45\u201d en el mundo jugar\u00e1n en el Mayakoba Golf Classic de este a\u00f1o, incluyendo Rickie Fowler, Tony Finau, Kevin Kisner, Billy Horschel, Matt Kuchar, Brian Harman y Charley Hoffman.<\/p>\n<p>Representando a M\u00e9xico se encuentran Abraham Ancer, Roberto D\u00edaz, Carlos Ortiz, Jos\u00e9 de Jes\u00fas Rodr\u00edguez, Oscar Fraustro y Armando Favela.<\/p>\n<p>Los asistentes tambi\u00e9n tendr\u00e1n la oportunidad de disfrutar de la cultura y la comida de M\u00e9xico, as\u00ed como del tequila, presentado por Tequila Patron.<\/p>\n<p>Para comprar boletos y obtener m\u00e1s informaci\u00f3n, visite: <a href=\"https:\/\/mayakobagolfclassic.com\/\">mayakobagolfclassic.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento de este a\u00f1o, que se llevar\u00e1 a cabo del 5 al 11 de noviembre, contar\u00e1 con la presencia de 132 golfistas profesionales, incluyendo a importantes jugadores como Jordan Speith, Rickie Fowler, Tony Finau y m\u00e1s.<\/p>\n","protected":false},"author":4,"featured_media":34111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1167,1164],"tags":[],"class_list":["post-34132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diviertase-4","category-playa-del-carmen-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico\" \/>\n<meta property=\"og:description\" content=\"El evento de este a\u00f1o, que se llevar\u00e1 a cabo del 5 al 11 de noviembre, contar\u00e1 con la presencia de 132 golfistas profesionales, incluyendo a importantes jugadores como Jordan Speith, Rickie Fowler, Tony Finau y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-05T17:25:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-06T04:59:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Belen Molina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@inmexicocom\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Belen Molina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\"},\"author\":{\"name\":\"Belen Molina\",\"@id\":\"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\"},\"headline\":\"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores\",\"datePublished\":\"2018-11-05T17:25:59+00:00\",\"dateModified\":\"2018-11-06T04:59:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\"},\"wordCount\":312,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg\",\"articleSection\":[\"Divi\u00e9rtase\",\"Playa del Carmen &amp; Tulum\"],\"inLanguage\":\"es-MX\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\",\"url\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\",\"name\":\"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico\",\"isPartOf\":{\"@id\":\"http:\/\/54.148.48.30\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg\",\"datePublished\":\"2018-11-05T17:25:59+00:00\",\"dateModified\":\"2018-11-06T04:59:46+00:00\",\"author\":{\"@id\":\"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage\",\"url\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg\",\"contentUrl\":\"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg\",\"width\":1296,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/54.148.48.30\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/54.148.48.30\/es\/#website\",\"url\":\"http:\/\/54.148.48.30\/es\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/54.148.48.30\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695\",\"name\":\"Belen Molina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"http:\/\/54.148.48.30\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g\",\"caption\":\"Belen Molina\"},\"url\":\"https:\/\/www.inmexico.com\/es\/author\/belen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/","og_locale":"es_MX","og_type":"article","og_title":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico","og_description":"El evento de este a\u00f1o, que se llevar\u00e1 a cabo del 5 al 11 de noviembre, contar\u00e1 con la presencia de 132 golfistas profesionales, incluyendo a importantes jugadores como Jordan Speith, Rickie Fowler, Tony Finau y m\u00e1s.","og_url":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","article_published_time":"2018-11-05T17:25:59+00:00","article_modified_time":"2018-11-06T04:59:46+00:00","og_image":[{"width":1296,"height":770,"url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg","type":"image\/jpeg"}],"author":"Belen Molina","twitter_card":"summary_large_image","twitter_creator":"@inmexicocom","twitter_site":"@inmexicocom","twitter_misc":{"Written by":"Belen Molina","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#article","isPartOf":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/"},"author":{"name":"Belen Molina","@id":"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695"},"headline":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores","datePublished":"2018-11-05T17:25:59+00:00","dateModified":"2018-11-06T04:59:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/"},"wordCount":312,"commentCount":0,"image":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg","articleSection":["Divi\u00e9rtase","Playa del Carmen &amp; Tulum"],"inLanguage":"es-MX"},{"@type":"WebPage","@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/","url":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/","name":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores - InMexico","isPartOf":{"@id":"http:\/\/54.148.48.30\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage"},"image":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg","datePublished":"2018-11-05T17:25:59+00:00","dateModified":"2018-11-06T04:59:46+00:00","author":{"@id":"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695"},"breadcrumb":{"@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#primaryimage","url":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg","contentUrl":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2018\/11\/Screen-Shot-2018-11-05-at-9.56.45-AM.jpg","width":1296,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/www.inmexico.com\/es\/playa-del-carmen-es\/el-mayakoba-golf-classic-regresa-a-la-riviera-maya-con-los-mejores-jugadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/54.148.48.30\/"},{"@type":"ListItem","position":2,"name":"El Mayakoba Golf Classic regresa a la Riviera Maya con los mejores jugadores"}]},{"@type":"WebSite","@id":"http:\/\/54.148.48.30\/es\/#website","url":"http:\/\/54.148.48.30\/es\/","name":"InMexico","description":"Luxury Without Limits","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/54.148.48.30\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Person","@id":"http:\/\/54.148.48.30\/es\/#\/schema\/person\/cb207ad3844276a4e7b838ffbf8d9695","name":"Belen Molina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"http:\/\/54.148.48.30\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e59e75d3b3ccd747a1f8fe1a1e2c9a283dcdcd721b830ecc662eeccbc83e0b7?s=96&d=mm&r=g","caption":"Belen Molina"},"url":"https:\/\/www.inmexico.com\/es\/author\/belen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/34132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/comments?post=34132"}],"version-history":[{"count":1,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/34132\/revisions"}],"predecessor-version":[{"id":34133,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/posts\/34132\/revisions\/34133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media\/34111"}],"wp:attachment":[{"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/media?parent=34132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/categories?post=34132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inmexico.com\/es\/wp-json\/wp\/v2\/tags?post=34132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}